{"id":167176,"date":"2015-11-23T14:02:30","date_gmt":"2015-11-23T08:32:30","guid":{"rendered":"http:\/\/www.123telugu.com\/telugu\/?p=167176"},"modified":"2015-11-23T14:02:30","modified_gmt":"2015-11-23T08:32:30","slug":"manchu-vishnus-surprises-with-sarada-first-look","status":"publish","type":"post","link":"https:\/\/www.123telugu.com\/telugu\/news\/manchu-vishnus-surprises-with-sarada-first-look.html","title":{"rendered":"\u0c38\u0c3f\u0c15\u0c4d\u0c38\u0c4d \u0c2a\u0c4d\u0c2f\u0c3e\u0c15\u0c4d \u0c32\u0c41\u0c15\u0c4d \u0c24\u0c4b \u0c38\u0c30\u0c4d\u0c2a\u0c4d\u0c30\u0c48\u0c1c\u0c4d \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41"},"content":{"rendered":"<p><a href=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/sarada.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/sarada.jpg\" alt=\"sarada\" width=\"350\" height=\"497\" class=\"aligncenter size-full wp-image-167177\" srcset=\"https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/sarada.jpg 350w, https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/sarada-211x300.jpg 211w, https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/sarada-156x222.jpg 156w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a><br \/>\n\u0c24\u0c46\u0c32\u0c41\u0c17\u0c41 \u0c2a\u0c4d\u0c30\u0c47\u0c15\u0c4d\u0c37\u0c15\u0c41\u0c32\u0c15\u0c41 \u0c2c\u0c3e\u0c17\u0c3e \u0c24\u0c15\u0c4d\u0c15\u0c41\u0c35 \u0c2a\u0c30\u0c3f\u0c1a\u0c2f\u0c02 \u0c09\u0c28\u0c4d\u0c28 \u0c2f\u0c3e\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c25\u0c4d\u0c30\u0c3f\u0c32\u0c4d\u0c32\u0c30\u0c4d \u0c1c\u0c3e\u0c28\u0c30\u0c4d\u0c32\u0c4b &#8216;\u0c21\u0c48\u0c28\u0c2e\u0c48\u0c1f\u0c4d&#8217; \u0c32\u0c3e\u0c02\u0c1f\u0c3f \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c39\u0c40\u0c30\u0c4b \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41 &#8216;\u0c05\u0c21\u0c4d\u0c21\u0c3e&#8217; \u0c2b\u0c47\u0c2e\u0c4d \u0c1c\u0c3f.\u0c15\u0c3e\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c4d \u0c30\u0c46\u0c21\u0c4d\u0c21\u0c3f \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c24\u0c4d\u0c35\u0c02\u0c32\u0c4b \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e &#8216;\u0c38\u0c30\u0c26\u0c3e&#8217;. \u0c36\u0c4d\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c36\u0c4d\u0c35\u0c30 \u0c38\u0c4d\u0c35\u0c3e\u0c2e\u0c3f \u0c2b\u0c3f\u0c32\u0c3f\u0c02\u0c38\u0c4d \u0c2c\u0c4d\u0c2f\u0c3e\u0c28\u0c30\u0c4d \u0c2a\u0c48 \u0c21\u0c3f.\u0c15\u0c41\u0c2e\u0c3e\u0c30\u0c4d\u200c &#8211; \u0c2a\u0c32\u0c4d\u0c32\u0c3f \u0c15\u0c47\u0c36\u0c35\u0c30\u0c3e\u0c35\u0c41 \u0c38\u0c02\u0c2f\u0c41\u0c15\u0c4d\u0c24\u0c02\u0c17\u0c3e \u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b &#8216;\u0c1c\u0c3e\u0c26\u0c42\u0c17\u0c3e\u0c21\u0c41&#8217; \u0c2b\u0c47\u0c2e\u0c4d \u0c38\u0c4b\u0c28\u0c3e\u0c30\u0c3f\u0c15 \u0c2c\u0c21\u0c4b\u0c30\u0c3f\u0c2f\u0c3e  \u0c39\u0c40\u0c30\u0c4b\u0c2f\u0c3f\u0c28\u0c4d \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c15\u0c47 \u0c30\u0c46\u0c02\u0c21\u0c41 \u0c37\u0c46\u0c21\u0c4d\u0c2f\u0c42\u0c32\u0c4d\u0c38\u0c4d \u0c28\u0c3f \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30 \u0c1f\u0c40\u0c02 \u0c2e\u0c42\u0c21\u0c35 \u0c37\u0c46\u0c21\u0c4d\u0c2f\u0c42\u0c32\u0c4d \u0c15\u0c4b\u0c38\u0c02 \u0c38\u0c3f\u0c26\u0c4d\u0c26\u0c2e\u0c35\u0c41\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c2e\u0c30\u0c4b \u0c15\u0c40\u0c32\u0c15 \u0c2a\u0c3e\u0c24\u0c4d\u0c30 \u0c15\u0c4b\u0c38\u0c02 \u0c13 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c39\u0c40\u0c30\u0c4b\u0c2f\u0c3f\u0c28\u0c4d \u0c28\u0c3f \u0c05\u0c28\u0c4d\u0c35\u0c47\u0c37\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c05\u0c02\u0c26\u0c41\u0c32\u0c4b \u0c2d\u0c3e\u0c17\u0c02\u0c17\u0c3e\u0c28\u0c47 \u0c05\u0c2e\u0c32\u0c3e \u0c2a\u0c3e\u0c32\u0c4d \u0c28\u0c3f \u0c15\u0c42\u0c21\u0c3e \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. <\/p>\n<p>\u0c07\u0c26\u0c3f\u0c32\u0c3e \u0c09\u0c02\u0c1f\u0c47 \u0c08 \u0c30\u0c4b\u0c1c\u0c41 \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41 \u0c2c\u0c30\u0c4d\u0c24\u0c4d \u0c21\u0c47.. \u0c2c\u0c30\u0c4d\u0c24\u0c4d \u0c21\u0c47 \u0c15\u0c3e\u0c28\u0c41\u0c15\u0c17\u0c3e \u0c38\u0c30\u0c26\u0c3e \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b\u0c28\u0c3f \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41 \u0c38\u0c3f\u0c15\u0c4d\u0c38\u0c4d \u0c2a\u0c4d\u0c2f\u0c3e\u0c15\u0c4d \u0c32\u0c41\u0c15\u0c4d \u0c38\u0c4d\u0c1f\u0c3f\u0c32\u0c4d \u0c28\u0c3f \u0c2b\u0c38\u0c4d\u0c1f\u0c4d \u0c32\u0c41\u0c15\u0c4d \u0c17\u0c3e \u0c30\u0c3f\u0c32\u0c40\u0c1c\u0c4d \u0c1a\u0c47\u0c38\u0c3e\u0c30\u0c41. \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41 \u0c24\u0c28 \u0c2c\u0c3e\u0c21\u0c40\u0c28\u0c3f \u0c2b\u0c41\u0c32\u0c4d \u0c17\u0c3e \u0c1f\u0c4b\u0c28\u0c4d \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c35\u0c3f\u0c27\u0c3e\u0c28\u0c02, \u0c24\u0c28 6 \u0c2a\u0c4d\u0c2f\u0c3e\u0c15\u0c4d \u0c32\u0c41\u0c15\u0c4d \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c28\u0c40 \u0c38\u0c30\u0c4d\u0c2a\u0c4d\u0c30\u0c48\u0c1c\u0c4d \u0c1a\u0c47\u0c2f\u0c21\u0c2e\u0c47 \u0c15\u0c3e\u0c15\u0c41\u0c02\u0c21\u0c3e \u0c38\u0c4b\u0c37\u0c32\u0c4d \u0c2e\u0c40\u0c21\u0c3f\u0c2f\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c4d\u0c1a\u0c28\u0c40\u0c2f\u0c3e\u0c02\u0c36\u0c02\u0c17\u0c3e \u0c2e\u0c3e\u0c30\u0c3f\u0c02\u0c26\u0c3f. \u0c08 \u0c32\u0c41\u0c15\u0c4d \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c39\u0c48 \u0c35\u0c4b\u0c32\u0c4d\u0c1f\u0c47\u0c1c\u0c4d \u0c2f\u0c3e\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c0e\u0c2a\u0c3f\u0c38\u0c4b\u0c21\u0c4d\u0c38\u0c4d \u0c15\u0c42\u0c21\u0c3e \u0c09\u0c02\u0c1f\u0c3e\u0c2f\u0c28\u0c3f \u0c06\u0c36\u0c3f\u0c02\u0c1a\u0c35\u0c1a\u0c4d\u0c1a\u0c41. \u0c32\u0c35\u0c4d \u0c05\u0c02\u0c21\u0c4d \u0c2f\u0c3e\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c0e\u0c02\u0c1f\u0c30\u0c4d\u0c1f\u0c48\u0c28\u0c30\u0c4d \u0c17\u0c3e \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c41\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c2c\u0c4d\u0c30\u0c39\u0c4d\u0c2e\u0c3e\u0c28\u0c02\u0c26\u0c02, \u0c1c\u0c2f\u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c37\u0c4d\u200c\u0c30\u0c46\u0c21\u0c4d\u0c21\u0c3f, \u0c30\u0c35\u0c3f\u0c15\u0c3f\u0c37\u0c28\u0c4d\u200c, \u0c2a\u0c43\u0c25\u0c4d\u0c35\u0c40, \u0c35\u0c46\u0c28\u0c4d\u0c28\u0c46\u0c32\u0c15\u0c3f\u0c37\u0c4b\u0c30\u0c4d\u200c, \u0c36\u0c4d\u0c30\u0c40\u0c28\u0c3f\u0c35\u0c3e\u0c38\u0c4d\u200c\u0c30\u0c46\u0c21\u0c4d\u0c21\u0c3f \u0c2e\u0c41\u0c16\u0c4d\u0c2f \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c41 \u0c2a\u0c4b\u0c37\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c05\u0c28\u0c42\u0c2a\u0c4d \u0c30\u0c42\u0c2c\u0c46\u0c28\u0c4d\u0c38\u0c4d \u0c2e\u0c4d\u0c2f\u0c42\u0c1c\u0c3f\u0c15\u0c4d \u0c05\u0c02\u0c26\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41.<\/p>\n<p>\u0c08 \u0c30\u0c4b\u0c1c\u0c41 \u0c2a\u0c41\u0c1f\u0c4d\u0c1f\u0c3f\u0c28 \u0c30\u0c4b\u0c1c\u0c41 \u0c1c\u0c30\u0c41\u0c2a\u0c41\u0c15\u0c41\u0c02\u0c1f\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41\u0c15\u0c3f 123\u0c24\u0c46\u0c32\u0c41\u0c17\u0c41.\u0c15\u0c3e\u0c2e\u0c4d \u0c24\u0c30\u0c2a\u0c41\u0c28 \u0c1c\u0c28\u0c4d\u0c2e\u0c26\u0c3f\u0c28 \u0c36\u0c41\u0c2d\u0c3e\u0c15\u0c3e\u0c02\u0c15\u0c4d\u0c37\u0c32\u0c41 \u0c24\u0c46\u0c32\u0c3f\u0c2f\u0c1c\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c02. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0c24\u0c46\u0c32\u0c41\u0c17\u0c41 \u0c2a\u0c4d\u0c30\u0c47\u0c15\u0c4d\u0c37\u0c15\u0c41\u0c32\u0c15\u0c41 \u0c2c\u0c3e\u0c17\u0c3e \u0c24\u0c15\u0c4d\u0c15\u0c41\u0c35 \u0c2a\u0c30\u0c3f\u0c1a\u0c2f\u0c02 \u0c09\u0c28\u0c4d\u0c28 \u0c2f\u0c3e\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c25\u0c4d\u0c30\u0c3f\u0c32\u0c4d\u0c32\u0c30\u0c4d \u0c1c\u0c3e\u0c28\u0c30\u0c4d\u0c32\u0c4b &#8216;\u0c21\u0c48\u0c28\u0c2e\u0c48\u0c1f\u0c4d&#8217; \u0c32\u0c3e\u0c02\u0c1f\u0c3f \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c39\u0c40\u0c30\u0c4b \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c2e\u0c02\u0c1a\u0c41 \u0c35\u0c3f\u0c37\u0c4d\u0c23\u0c41 &#8216;\u0c05\u0c21\u0c4d\u0c21\u0c3e&#8217; \u0c2b\u0c47\u0c2e\u0c4d \u0c1c\u0c3f.\u0c15\u0c3e\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c4d \u0c30\u0c46\u0c21\u0c4d\u0c21\u0c3f \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c24\u0c4d\u0c35\u0c02\u0c32\u0c4b \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e &#8216;\u0c38\u0c30\u0c26\u0c3e&#8217;. \u0c36\u0c4d\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c36\u0c4d\u0c35\u0c30 \u0c38\u0c4d\u0c35\u0c3e\u0c2e\u0c3f \u0c2b\u0c3f\u0c32\u0c3f\u0c02\u0c38\u0c4d \u0c2c\u0c4d\u0c2f\u0c3e\u0c28\u0c30\u0c4d \u0c2a\u0c48 \u0c21\u0c3f.\u0c15\u0c41\u0c2e\u0c3e\u0c30\u0c4d\u200c &#8211; \u0c2a\u0c32\u0c4d\u0c32\u0c3f \u0c15\u0c47\u0c36\u0c35\u0c30\u0c3e\u0c35\u0c41 \u0c38\u0c02\u0c2f\u0c41\u0c15\u0c4d\u0c24\u0c02\u0c17\u0c3e \u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b &#8216;\u0c1c\u0c3e\u0c26\u0c42\u0c17\u0c3e\u0c21\u0c41&#8217; \u0c2b\u0c47\u0c2e\u0c4d \u0c38\u0c4b\u0c28\u0c3e\u0c30\u0c3f\u0c15 \u0c2c\u0c21\u0c4b\u0c30\u0c3f\u0c2f\u0c3e \u0c39\u0c40\u0c30\u0c4b\u0c2f\u0c3f\u0c28\u0c4d \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c15\u0c47 \u0c30\u0c46\u0c02\u0c21\u0c41 \u0c37\u0c46\u0c21\u0c4d\u0c2f\u0c42\u0c32\u0c4d\u0c38\u0c4d \u0c28\u0c3f \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c08 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,4],"tags":[],"class_list":{"0":"post-167176","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-news","7":"category-mnews"},"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/167176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/comments?post=167176"}],"version-history":[{"count":0,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/167176\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/media?parent=167176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/categories?post=167176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/tags?post=167176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}