{"id":168643,"date":"2015-12-07T08:30:52","date_gmt":"2015-12-07T03:00:52","guid":{"rendered":"http:\/\/www.123telugu.com\/telugu\/?p=168643"},"modified":"2015-12-07T08:30:52","modified_gmt":"2015-12-07T03:00:52","slug":"nannaku-prematho-audio-release-date","status":"publish","type":"post","link":"https:\/\/www.123telugu.com\/telugu\/news\/nannaku-prematho-audio-release-date.html","title":{"rendered":"&#8216;\u0c28\u0c3e\u0c28\u0c4d\u0c28\u0c15\u0c41 \u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c24\u0c4b&#8217; \u0c06\u0c21\u0c3f\u0c2f\u0c4b \u0c30\u0c3f\u0c32\u0c40\u0c1c\u0c4d \u0c21\u0c47\u0c1f\u0c4d?"},"content":{"rendered":"<p><a href=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/Nannaku-Prematho1.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/Nannaku-Prematho1.jpg\" alt=\"Nannaku-Prematho\" width=\"450\" height=\"300\" class=\"aligncenter size-full wp-image-166139\" srcset=\"https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/Nannaku-Prematho1.jpg 450w, https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/Nannaku-Prematho1-300x200.jpg 300w, https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2015\/11\/Nannaku-Prematho1-333x222.jpg 333w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><br \/>\n\u0c2f\u0c02\u0c17\u0c4d \u0c1f\u0c48\u0c17\u0c30\u0c4d \u0c0e\u0c28\u0c4d.\u0c1f\u0c3f.\u0c06\u0c30\u0c4d \u0c38\u0c41\u0c15\u0c41\u0c2e\u0c3e\u0c30\u0c4d \u0c21\u0c48\u0c30\u0c46\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c32\u0c4b \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 25\u0c35 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e &#8216;\u0c28\u0c3e\u0c28\u0c4d\u0c28\u0c15\u0c41 \u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c24\u0c4b&#8217;. \u0c38\u0c42\u0c2a\u0c30\u0c4d \u0c15\u0c4d\u0c32\u0c3e\u0c38\u0c4d \u0c2f\u0c3e\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c0e\u0c02\u0c1f\u0c30\u0c4d\u0c1f\u0c48\u0c28\u0c30\u0c4d \u0c30\u0c3e\u0c28\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c05\u0c02\u0c26\u0c3e\u0c32 \u0c2d\u0c3e\u0c2e \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c39\u0c40\u0c30\u0c4b\u0c2f\u0c3f\u0c28\u0c4d \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c26\u0c38\u0c30\u0c3e \u0c15\u0c3e\u0c28\u0c41\u0c15\u0c17\u0c3e \u0c30\u0c3f\u0c32\u0c40\u0c1c\u0c4d \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c1f\u0c40\u0c1c\u0c30\u0c4d \u0c15\u0c3f \u0c05\u0c26\u0c3f\u0c30\u0c3f\u0c2a\u0c4b\u0c2f\u0c47 \u0c30\u0c46\u0c38\u0c4d\u0c2a\u0c3e\u0c28\u0c4d\u0c38\u0c4d \u0c30\u0c3e\u0c35\u0c21\u0c2e\u0c47 \u0c15\u0c3e\u0c15\u0c41\u0c02\u0c21\u0c3e \u0c2f\u0c41 \u0c1f\u0c4d\u0c2f\u0c42\u0c2c\u0c4d \u0c32\u0c4b \u0c38\u0c46\u0c28\u0c4d\u0c38\u0c47\u0c37\u0c28\u0c32\u0c4d \u0c30\u0c3f\u0c15\u0c3e\u0c30\u0c4d\u0c21\u0c4d\u0c38\u0c4d \u0c38\u0c43\u0c37\u0c4d\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2b\u0c48\u0c28\u0c32\u0c4d \u0c37\u0c46\u0c21\u0c4d\u0c2f\u0c42\u0c32\u0c4d \u0c38\u0c4d\u0c2a\u0c46\u0c2f\u0c3f\u0c28\u0c4d \u0c32\u0c4b \u0c1c\u0c30\u0c41\u0c17\u0c41\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c26\u0c3e\u0c26\u0c3e\u0c2a\u0c41 \u0c21\u0c3f\u0c38\u0c46\u0c02\u0c2c\u0c30\u0c4d 20\u0c35\u0c30\u0c15\u0c42 \u0c1c\u0c30\u0c17\u0c28\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c37\u0c46\u0c21\u0c4d\u0c2f\u0c42\u0c32\u0c4d \u0c24\u0c4b \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c24\u0c4d\u0c24\u0c02 \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c3f. <\/p>\n<p>\u0c24\u0c3e\u0c1c\u0c3e \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30 \u0c1f\u0c40\u0c02 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c06\u0c21\u0c3f\u0c2f\u0c4b \u0c30\u0c3f\u0c32\u0c40\u0c1c\u0c4d \u0c15\u0c3f \u0c21\u0c47\u0c1f\u0c4d \u0c2b\u0c3f\u0c15\u0c4d\u0c38\u0c4d \u0c1a\u0c47\u0c38\u0c3f\u0c28\u0c1f\u0c4d\u0c32\u0c41 \u0c2b\u0c3f\u0c32\u0c4d\u0c2e\u0c4d \u0c28\u0c30\u0c17\u0c4d\u0c32\u0c4b \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41 \u0c35\u0c3f\u0c28\u0c3f\u0c2a\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f. \u0c35\u0c3e\u0c30\u0c41 \u0c1a\u0c46\u0c2c\u0c41\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c26\u0c3e\u0c28\u0c3f \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c21\u0c3f\u0c38\u0c46\u0c02\u0c2c\u0c30\u0c4d 25\u0c28 \u0c28\u0c3e\u0c28\u0c4d\u0c28\u0c15\u0c41 \u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c24\u0c4b \u0c06\u0c21\u0c3f\u0c2f\u0c4b\u0c28\u0c3f \u0c30\u0c3f\u0c32\u0c40\u0c1c\u0c4d \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c38\u0c02\u0c15\u0c4d\u0c30\u0c3e\u0c02\u0c24\u0c3f \u0c30\u0c3f\u0c32\u0c40\u0c1c\u0c4d \u0c15\u0c3f \u0c38\u0c2e\u0c2f\u0c02 \u0c26\u0c17\u0c4d\u0c17\u0c30 \u0c2a\u0c21\u0c41\u0c24\u0c41\u0c02\u0c21\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c15\u0c3e\u0c32 \u0c2a\u0c28\u0c41\u0c32\u0c28\u0c41 \u0c35\u0c47\u0c17\u0c35\u0c02\u0c24\u0c02 \u0c1a\u0c47\u0c38\u0c3f\u0c02\u0c26\u0c3f \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30 \u0c1f\u0c40\u0c02. \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c1c\u0c30\u0c41\u0c17\u0c41\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c15\u0c40 \u0c2e\u0c3f\u0c17\u0c24\u0c3e \u0c2b\u0c3f\u0c28\u0c3f\u0c37\u0c4d \u0c05\u0c2f\u0c3f\u0c28 \u0c2a\u0c3e\u0c30\u0c4d\u0c1f\u0c4d \u0c15\u0c3f \u0c38\u0c02\u0c2c\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c2a\u0c4b\u0c38\u0c4d\u0c1f\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c35\u0c30\u0c4d\u0c15\u0c4d \u0c28\u0c3f \u0c36\u0c30\u0c35\u0c47\u0c17\u0c02\u0c17\u0c3e \u0c2b\u0c3f\u0c28\u0c3f\u0c37\u0c4d \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c1c\u0c17\u0c2a\u0c24\u0c3f \u0c2c\u0c3e\u0c2c\u0c41, \u0c30\u0c3e\u0c1c\u0c47\u0c02\u0c26\u0c4d\u0c30 \u0c2a\u0c4d\u0c30\u0c38\u0c3e\u0c26\u0c4d \u0c32\u0c41 \u0c2e\u0c41\u0c16\u0c4d\u0c2f \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c41 \u0c2a\u0c4b\u0c37\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c3f \u0c2c\u0c3f\u0c35\u0c3f\u0c0e\u0c38\u0c4d\u0c0e\u0c28\u0c4d \u0c2a\u0c4d\u0c30\u0c38\u0c3e\u0c26\u0c4d \u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c38\u0c41\u0c15\u0c41\u0c2e\u0c3e\u0c30\u0c4d \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c24\u0c4d\u0c35\u0c02 \u0c35\u0c39\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c3f \u0c26\u0c47\u0c35\u0c40\u0c36\u0c4d\u0c30\u0c40 \u0c2a\u0c4d\u0c30\u0c38\u0c3e\u0c26\u0c4d \u0c2e\u0c4d\u0c2f\u0c42\u0c1c\u0c3f\u0c15\u0c4d \u0c05\u0c02\u0c26\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0c2f\u0c02\u0c17\u0c4d \u0c1f\u0c48\u0c17\u0c30\u0c4d \u0c0e\u0c28\u0c4d.\u0c1f\u0c3f.\u0c06\u0c30\u0c4d \u0c38\u0c41\u0c15\u0c41\u0c2e\u0c3e\u0c30\u0c4d \u0c21\u0c48\u0c30\u0c46\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c32\u0c4b \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 25\u0c35 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e &#8216;\u0c28\u0c3e\u0c28\u0c4d\u0c28\u0c15\u0c41 \u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c24\u0c4b&#8217;. \u0c38\u0c42\u0c2a\u0c30\u0c4d \u0c15\u0c4d\u0c32\u0c3e\u0c38\u0c4d \u0c2f\u0c3e\u0c15\u0c4d\u0c37\u0c28\u0c4d \u0c0e\u0c02\u0c1f\u0c30\u0c4d\u0c1f\u0c48\u0c28\u0c30\u0c4d \u0c30\u0c3e\u0c28\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c05\u0c02\u0c26\u0c3e\u0c32 \u0c2d\u0c3e\u0c2e \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c39\u0c40\u0c30\u0c4b\u0c2f\u0c3f\u0c28\u0c4d \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c26\u0c38\u0c30\u0c3e \u0c15\u0c3e\u0c28\u0c41\u0c15\u0c17\u0c3e \u0c30\u0c3f\u0c32\u0c40\u0c1c\u0c4d \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c1f\u0c40\u0c1c\u0c30\u0c4d \u0c15\u0c3f \u0c05\u0c26\u0c3f\u0c30\u0c3f\u0c2a\u0c4b\u0c2f\u0c47 \u0c30\u0c46\u0c38\u0c4d\u0c2a\u0c3e\u0c28\u0c4d\u0c38\u0c4d \u0c30\u0c3e\u0c35\u0c21\u0c2e\u0c47 \u0c15\u0c3e\u0c15\u0c41\u0c02\u0c21\u0c3e \u0c2f\u0c41 \u0c1f\u0c4d\u0c2f\u0c42\u0c2c\u0c4d \u0c32\u0c4b \u0c38\u0c46\u0c28\u0c4d\u0c38\u0c47\u0c37\u0c28\u0c32\u0c4d \u0c30\u0c3f\u0c15\u0c3e\u0c30\u0c4d\u0c21\u0c4d\u0c38\u0c4d \u0c38\u0c43\u0c37\u0c4d\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2b\u0c48\u0c28\u0c32\u0c4d \u0c37\u0c46\u0c21\u0c4d\u0c2f\u0c42\u0c32\u0c4d \u0c38\u0c4d\u0c2a\u0c46\u0c2f\u0c3f\u0c28\u0c4d \u0c32\u0c4b \u0c1c\u0c30\u0c41\u0c17\u0c41\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c26\u0c3e\u0c26\u0c3e\u0c2a\u0c41 \u0c21\u0c3f\u0c38\u0c46\u0c02\u0c2c\u0c30\u0c4d 20\u0c35\u0c30\u0c15\u0c42 \u0c1c\u0c30\u0c17\u0c28\u0c41\u0c28\u0c4d\u0c28 \u0c08 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,4],"tags":[],"class_list":{"0":"post-168643","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-news","7":"category-mnews"},"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/168643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/comments?post=168643"}],"version-history":[{"count":0,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/168643\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/media?parent=168643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/categories?post=168643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/tags?post=168643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}