{"id":292566,"date":"2018-10-24T18:27:50","date_gmt":"2018-10-24T12:57:50","guid":{"rendered":"https:\/\/www.123telugu.com\/telugu\/?p=292566"},"modified":"2018-10-24T18:28:15","modified_gmt":"2018-10-24T12:58:15","slug":"venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date","status":"publish","type":"post","link":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html","title":{"rendered":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b  &#8216;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#8217; \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !"},"content":{"rendered":"<p><a href=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai8.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai8.jpg\" alt=\"\" width=\"450\" height=\"300\" class=\"aligncenter size-full wp-image-292567\" srcset=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai8.jpg 450w, https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai8-300x200.jpg 300w, https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai8-333x222.jpg 333w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f  \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b  &#8216;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#8217; \u0c05\u0c28\u0c47  \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e  &#8216;\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d&#8217; \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28  \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b  \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f.   <\/p>\n<p>\u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32  \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02  \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d  \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f.  \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d  \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41  \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e..  \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f  \u0c2c\u0c3e\u0c32\u0c40\u0c35\u0c41\u0c21\u0c4d \u0c2c\u0c4d\u0c2f\u0c42\u0c1f\u0c40 \u0c39\u0c41\u0c2e\u0c3e \u0c16\u0c41\u0c30\u0c47\u0c37\u0c3f \u0c1c\u0c4b\u0c21\u0c3f\u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f.  \u0c2b\u0c41\u0c32\u0c4d \u0c15\u0c3e\u0c2e\u0c46\u0c21\u0c40 \u0c0e\u0c02\u0c1f\u0c30\u0c4d \u0c1f\u0c48\u0c28\u0c30\u0c4d \u0c17\u0c3e \u0c30\u0c4b\u0c2a\u0c4a\u0c02\u0c26\u0c28\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b  \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d \u0c15\u0c4d\u0c2f\u0c3e\u0c30\u0c46\u0c15\u0c4d\u0c1f\u0c30\u0c4d \u0c1a\u0c3e\u0c32\u0c3e \u0c07\u0c02\u0c1f\u0c4d\u0c30\u0c38\u0c4d\u0c1f\u0c4d \u0c17\u0c3e \u0c09\u0c02\u0c21\u0c28\u0c41\u0c02\u0c26\u0c1f.   \u0c05\u0c32\u0c3e\u0c17\u0c47 \u0c28\u0c3e\u0c17 \u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f  \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d \u0c15\u0c3e\u0c02\u0c2c\u0c3f\u0c28\u0c47\u0c37\u0c28\u0c4d \u0c32\u0c4b \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c38\u0c28\u0c4d\u0c28\u0c3f\u0c35\u0c47\u0c36\u0c3e\u0c32\u0c41 \u0c15\u0c42\u0c21\u0c3e \u0c2c\u0c3e\u0c17\u0c3e \u0c28\u0c35\u0c4d\u0c35\u0c3f\u0c38\u0c4d\u0c24\u0c3e\u0c2f\u0c28\u0c3f \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02.  <\/p>\n<p>&#8216;\u0c1c\u0c48 \u0c32\u0c35 \u0c15\u0c41\u0c36 &#8216; \u0c1a\u0c3f\u0c24\u0c4d\u0c30  \u0c21\u0c48\u0c30\u0c46\u0c15\u0c4d\u0c1f\u0c30\u0c4d \u0c2c\u0c3e\u0c2c\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c24\u0c4d\u0c35\u0c02\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c41\u0c24\u0c41\u0c02\u0c26\u0c3f.   \u0c2a\u0c4d\u0c30\u0c2e\u0c41\u0c16 \u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24  \u0c38\u0c41\u0c30\u0c47\u0c37\u0c4d  \u0c2c\u0c3e\u0c2c\u0c41\u0c24\u0c4b \u0c15\u0c32\u0c3f\u0c38\u0c3f \u0c15\u0c4b\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c4d \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c2a\u0c40\u0c2a\u0c41\u0c32\u0c4d\u0c38\u0c4d \u0c2e\u0c40\u0c21\u0c3f\u0c2f\u0c3e \u0c2b\u0c4d\u0c2f\u0c3e\u0c15\u0c4d\u0c1f\u0c30\u0c40\u0c32\u0c41 \u0c15\u0c32\u0c3f\u0c38\u0c3f \u0c38\u0c02\u0c2f\u0c41\u0c15\u0c4d\u0c24\u0c02\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b &#8216;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#8217; \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e &#8216;\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d&#8217; \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":292568,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,4,32],"tags":[],"class_list":["post-292566","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-mnews","category-featured"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b &#039;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#039; \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e &#039;\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d&#039; \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"123telugu\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Telugu Cinema News in Telugu\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b &#039;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#039; \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e &#039;\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d&#039; \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-10-24T12:57:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-10-24T12:58:15+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/123telugu\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@123telugu\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b &#039;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#039; \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e &#039;\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d&#039; \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#article\",\"name\":\"\\u0c28\\u0c35\\u0c02\\u0c2c\\u0c30\\u0c4d \\u0c32\\u0c4b \\u2018\\u0c35\\u0c46\\u0c02\\u0c15\\u0c40 \\u0c2e\\u0c3e\\u0c2e\\u2019 \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d !\",\"headline\":\"\\u0c28\\u0c35\\u0c02\\u0c2c\\u0c30\\u0c4d \\u0c32\\u0c4b  &#8216;\\u0c35\\u0c46\\u0c02\\u0c15\\u0c40 \\u0c2e\\u0c3e\\u0c2e&#8217; \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d !\",\"author\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/venky-chai-m.jpg\",\"width\":600,\"height\":400},\"datePublished\":\"2018-10-24T18:27:50+05:30\",\"dateModified\":\"2018-10-24T18:28:15+05:30\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#webpage\"},\"articleSection\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41, \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41, \\u0c38\\u0c4d\\u0c2a\\u0c46\\u0c37\\u0c32\\u0c4d \\u0c2b\\u0c40\\u0c1a\\u0c30\\u0c4d\\u0c38\\u0c4d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"position\":2,\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"position\":3,\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#listItem\",\"name\":\"\\u0c28\\u0c35\\u0c02\\u0c2c\\u0c30\\u0c4d \\u0c32\\u0c4b  &#8216;\\u0c35\\u0c46\\u0c02\\u0c15\\u0c40 \\u0c2e\\u0c3e\\u0c2e&#8217; \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d !\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#listItem\",\"position\":4,\"name\":\"\\u0c28\\u0c35\\u0c02\\u0c2c\\u0c30\\u0c4d \\u0c32\\u0c4b  &#8216;\\u0c35\\u0c46\\u0c02\\u0c15\\u0c40 \\u0c2e\\u0c3e\\u0c2e&#8217; \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d !\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\",\"name\":\"123telugu.com\",\"description\":\"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/new_big_tel.png\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/123teluguofficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew\",\"name\":\"123telugu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#webpage\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\",\"name\":\"\\u0c28\\u0c35\\u0c02\\u0c2c\\u0c30\\u0c4d \\u0c32\\u0c4b \\u2018\\u0c35\\u0c46\\u0c02\\u0c15\\u0c40 \\u0c2e\\u0c3e\\u0c2e\\u2019 \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d !\",\"description\":\"\\u0c35\\u0c3f\\u0c15\\u0c4d\\u0c1f\\u0c30\\u0c40 \\u0c35\\u0c46\\u0c02\\u0c15\\u0c1f\\u0c47\\u0c37\\u0c4d, \\u0c2f\\u0c41\\u0c35 \\u0c38\\u0c3e\\u0c2e\\u0c4d\\u0c30\\u0c3e\\u0c1f\\u0c4d \\u0c28\\u0c3e\\u0c17\\u0c1a\\u0c48\\u0c24\\u0c28\\u0c4d\\u0c2f \\u0c15\\u0c32\\u0c2f\\u0c3f\\u0c15\\u0c32\\u0c4b '\\u0c35\\u0c46\\u0c02\\u0c15\\u0c40 \\u0c2e\\u0c3e\\u0c2e' \\u0c05\\u0c28\\u0c47 \\u0c2e\\u0c32\\u0c4d\\u0c1f\\u0c40 \\u0c38\\u0c4d\\u0c1f\\u0c3e\\u0c30\\u0c30\\u0c4d \\u0c24\\u0c46\\u0c30\\u0c15\\u0c46\\u0c15\\u0c4d\\u0c15\\u0c28\\u0c41\\u0c28\\u0c4d\\u0c28\\u0c35\\u0c3f\\u0c37\\u0c2f\\u0c02 \\u0c24\\u0c46\\u0c32\\u0c3f\\u0c38\\u0c3f\\u0c02\\u0c26\\u0c47. \\u0c15\\u0c3e\\u0c17\\u0c3e '\\u0c2a\\u0c4d\\u0c30\\u0c47\\u0c2e\\u0c2e\\u0c4d' \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c32\\u0c4b \\u0c15\\u0c4a\\u0c26\\u0c4d\\u0c26\\u0c3f\\u0c38\\u0c47\\u0c2a\\u0c41 \\u0c38\\u0c4d\\u0c15\\u0c4d\\u0c30\\u0c40\\u0c28\\u0c4d \\u0c37\\u0c47\\u0c30\\u0c4d \\u0c1a\\u0c47\\u0c38\\u0c41\\u0c15\\u0c41\\u0c28\\u0c4d\\u0c28 \\u0c35\\u0c46\\u0c02\\u0c15\\u0c40, \\u0c1a\\u0c48\\u0c24\\u0c42\\u0c32\\u0c41 \\u0c07\\u0c2a\\u0c4d\\u0c2a\\u0c41\\u0c21\\u0c41 \\u0c2b\\u0c41\\u0c32\\u0c4d \\u0c32\\u0c46\\u0c02\\u0c17\\u0c4d\\u0c24\\u0c4d \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c32\\u0c4b \\u0c28\\u0c1f\\u0c3f\\u0c38\\u0c4d\\u0c24\\u0c41\\u0c02\\u0c21\\u0c02\\u0c24\\u0c4b \\u0c05\\u0c02\\u0c26\\u0c30\\u0c3f\\u0c32\\u0c4b\\u0c28\\u0c42 \\u0c06\\u0c38\\u0c15\\u0c4d\\u0c24\\u0c3f\\u0c28\\u0c3f \\u0c30\\u0c47\\u0c15\\u0c46\\u0c24\\u0c4d\\u0c24\\u0c3f\\u0c38\\u0c4d\\u0c24\\u0c4b\\u0c02\\u0c26\\u0c3f. \\u0c24\\u0c3e\\u0c1c\\u0c3e\\u0c17\\u0c3e \\u0c38\\u0c3f\\u0c28\\u0c40\\u0c35\\u0c30\\u0c4d\\u0c17\\u0c3e\\u0c32 \\u0c38\\u0c2e\\u0c3e\\u0c1a\\u0c3e\\u0c30\\u0c02 \\u0c2a\\u0c4d\\u0c30\\u0c15\\u0c3e\\u0c30\\u0c02 \\u0c08 \\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02 \\u0c28\\u0c35\\u0c02\\u0c2c\\u0c30\\u0c4d 12\\u0c35 \\u0c24\\u0c47\\u0c26\\u0c40 \\u0c28\\u0c41\\u0c02\\u0c21\\u0c3f \\u0c30\\u0c46\\u0c17\\u0c4d\\u0c2f\\u0c42\\u0c32\\u0c30\\u0c4d \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d \\u0c2e\\u0c4a\\u0c26\\u0c32\\u0c35\\u0c41\\u0c24\\u0c41\\u0c02\\u0c26\\u0c28\\u0c3f \\u0c24\\u0c46\\u0c32\\u0c41\\u0c38\\u0c4d\\u0c24\\u0c4b\\u0c02\\u0c26\\u0c3f. \\u0c15\\u0c3e\\u0c17\\u0c3e \\u0c08 \\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02\\u0c32\\u0c4b \\u0c30\\u0c15\\u0c41\\u0c32\\u0c4d \\u0c2a\\u0c4d\\u0c30\\u0c40\\u0c24\\u0c4d \\u0c38\\u0c3f\\u0c02\\u0c17\\u0c4d \\u0c1a\\u0c48\\u0c24\\u0c41\\u0c15\\u0c41 \\u0c1c\\u0c4b\\u0c21\\u0c3f \\u0c17\\u0c3e \\u0c28\\u0c1f\\u0c3f\\u0c38\\u0c4d\\u0c24\\u0c41\\u0c02\\u0c21\\u0c17\\u0c3e.. \\u0c35\\u0c46\\u0c02\\u0c15\\u0c40\\u0c15\\u0c3f\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/venky-chai-m.jpg\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\\\/#mainImage\",\"width\":600,\"height\":400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#mainImage\"},\"datePublished\":\"2018-10-24T18:27:50+05:30\",\"dateModified\":\"2018-10-24T18:28:15+05:30\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#website\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/\",\"name\":\"123telugu.com\",\"alternateName\":\"123telugu\",\"description\":\"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","description":"\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b '\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e' \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e '\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d' \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f","canonical_url":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#article","name":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","headline":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b  &#8216;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#8217; \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","author":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"publisher":{"@id":"https:\/\/www.123telugu.com\/telugu\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg","width":600,"height":400},"datePublished":"2018-10-24T18:27:50+05:30","dateModified":"2018-10-24T18:28:15+05:30","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#webpage"},"isPartOf":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#webpage"},"articleSection":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41, \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41, \u0c38\u0c4d\u0c2a\u0c46\u0c37\u0c32\u0c4d \u0c2b\u0c40\u0c1a\u0c30\u0c4d\u0c38\u0c4d"},{"@type":"BreadcrumbList","@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu#listItem","position":1,"name":"Home","item":"https:\/\/www.123telugu.com\/telugu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","position":2,"name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","item":"https:\/\/www.123telugu.com\/telugu\/category\/news","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","position":3,"name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","item":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#listItem","name":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b  &#8216;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#8217; \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#listItem","position":4,"name":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b  &#8216;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#8217; \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}}]},{"@type":"Organization","@id":"https:\/\/www.123telugu.com\/telugu\/#organization","name":"123telugu.com","description":"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings","url":"https:\/\/www.123telugu.com\/telugu\/","logo":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2019\/09\/new_big_tel.png","@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\/#organizationLogo"},"image":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/123teluguofficial\/"]},{"@type":"Person","@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author","url":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew","name":"123telugu"},{"@type":"WebPage","@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#webpage","url":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html","name":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","description":"\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b '\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e' \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e '\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d' \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.123telugu.com\/telugu\/#website"},"breadcrumb":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#breadcrumblist"},"author":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"creator":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"image":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg","@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html\/#mainImage","width":600,"height":400},"primaryImageOfPage":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html#mainImage"},"datePublished":"2018-10-24T18:27:50+05:30","dateModified":"2018-10-24T18:28:15+05:30"},{"@type":"WebSite","@id":"https:\/\/www.123telugu.com\/telugu\/#website","url":"https:\/\/www.123telugu.com\/telugu\/","name":"123telugu.com","alternateName":"123telugu","description":"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.123telugu.com\/telugu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Telugu Cinema News in Telugu","og:type":"article","og:title":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","og:description":"\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b '\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e' \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e '\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d' \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f","og:url":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html","og:image":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg","og:image:secure_url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg","article:published_time":"2018-10-24T12:57:50+00:00","article:modified_time":"2018-10-24T12:58:15+00:00","article:publisher":"https:\/\/www.facebook.com\/123telugu","twitter:card":"summary","twitter:site":"@123telugu","twitter:title":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","twitter:description":"\u0c35\u0c3f\u0c15\u0c4d\u0c1f\u0c30\u0c40 \u0c35\u0c46\u0c02\u0c15\u0c1f\u0c47\u0c37\u0c4d, \u0c2f\u0c41\u0c35 \u0c38\u0c3e\u0c2e\u0c4d\u0c30\u0c3e\u0c1f\u0c4d \u0c28\u0c3e\u0c17\u0c1a\u0c48\u0c24\u0c28\u0c4d\u0c2f \u0c15\u0c32\u0c2f\u0c3f\u0c15\u0c32\u0c4b '\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e' \u0c05\u0c28\u0c47 \u0c2e\u0c32\u0c4d\u0c1f\u0c40 \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c30\u0c4d \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c35\u0c3f\u0c37\u0c2f\u0c02 \u0c24\u0c46\u0c32\u0c3f\u0c38\u0c3f\u0c02\u0c26\u0c47. \u0c15\u0c3e\u0c17\u0c3e '\u0c2a\u0c4d\u0c30\u0c47\u0c2e\u0c2e\u0c4d' \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c3f\u0c38\u0c47\u0c2a\u0c41 \u0c38\u0c4d\u0c15\u0c4d\u0c30\u0c40\u0c28\u0c4d \u0c37\u0c47\u0c30\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c46\u0c02\u0c15\u0c40, \u0c1a\u0c48\u0c24\u0c42\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 \u0c2b\u0c41\u0c32\u0c4d \u0c32\u0c46\u0c02\u0c17\u0c4d\u0c24\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c02\u0c24\u0c4b \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c32\u0c4b\u0c28\u0c42 \u0c06\u0c38\u0c15\u0c4d\u0c24\u0c3f\u0c28\u0c3f \u0c30\u0c47\u0c15\u0c46\u0c24\u0c4d\u0c24\u0c3f\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c24\u0c3e\u0c1c\u0c3e\u0c17\u0c3e \u0c38\u0c3f\u0c28\u0c40\u0c35\u0c30\u0c4d\u0c17\u0c3e\u0c32 \u0c38\u0c2e\u0c3e\u0c1a\u0c3e\u0c30\u0c02 \u0c2a\u0c4d\u0c30\u0c15\u0c3e\u0c30\u0c02 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d 12\u0c35 \u0c24\u0c47\u0c26\u0c40 \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c42\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2e\u0c4a\u0c26\u0c32\u0c35\u0c41\u0c24\u0c41\u0c02\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c4b\u0c02\u0c26\u0c3f. \u0c15\u0c3e\u0c17\u0c3e \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c30\u0c15\u0c41\u0c32\u0c4d \u0c2a\u0c4d\u0c30\u0c40\u0c24\u0c4d \u0c38\u0c3f\u0c02\u0c17\u0c4d \u0c1a\u0c48\u0c24\u0c41\u0c15\u0c41 \u0c1c\u0c4b\u0c21\u0c3f \u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c21\u0c17\u0c3e.. \u0c35\u0c46\u0c02\u0c15\u0c40\u0c15\u0c3f","twitter:image":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg"},"aioseo_meta_data":{"post_id":"292566","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"custom_image","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"custom_image","twitter_image_url":null,"twitter_image_custom_url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/10\/venky-chai-m.jpg","twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-11 02:05:35","updated":"2022-10-11 18:07:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\/category\/news\" title=\"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41\">\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews\" title=\"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41\">\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b  \u2018\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e\u2019 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.123telugu.com\/telugu"},{"label":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","link":"https:\/\/www.123telugu.com\/telugu\/category\/news"},{"label":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","link":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews"},{"label":"\u0c28\u0c35\u0c02\u0c2c\u0c30\u0c4d \u0c32\u0c4b  &#8216;\u0c35\u0c46\u0c02\u0c15\u0c40 \u0c2e\u0c3e\u0c2e&#8217; \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d !","link":"https:\/\/www.123telugu.com\/telugu\/news\/venkatesh-and-naga-chaitanya-venky-mama-gets-a-start-date.html"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/292566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/comments?post=292566"}],"version-history":[{"count":0,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/292566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/media\/292568"}],"wp:attachment":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/media?parent=292566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/categories?post=292566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/tags?post=292566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}