{"id":294468,"date":"2018-11-07T15:30:10","date_gmt":"2018-11-07T10:00:10","guid":{"rendered":"https:\/\/www.123telugu.com\/telugu\/?p=294468"},"modified":"2018-11-07T15:48:49","modified_gmt":"2018-11-07T10:18:49","slug":"mr-majnu-will-be-release-in-next-year-january","status":"publish","type":"post","link":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html","title":{"rendered":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !"},"content":{"rendered":"<p><a href=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg\" alt=\"\" width=\"280\" height=\"397\" class=\"aligncenter size-full wp-image-294469\" srcset=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg 280w, https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue-212x300.jpg 212w, https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue-157x222.jpg 157w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/><\/a><\/p>\n<p> \u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02  &#8216;\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41&#8217; \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02  \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d  \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f.  \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15  \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d  \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f.   &#8216;\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e&#8217; \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41.   \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48  \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f  \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40  \u0c38\u0c47\u0c2a\u0c1f\u0c3f  \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e  \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41.  \u0c05\u0c2f\u0c3f\u0c24\u0c47  \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c38\u0c02\u0c15\u0c4d\u0c30\u0c3e\u0c02\u0c24\u0c3f \u0c2c\u0c30\u0c3f\u0c32\u0c4b \u0c28\u0c3f\u0c32\u0c3f\u0c1a\u0c47 \u0c05\u0c35\u0c15\u0c3e\u0c36\u0c02 \u0c32\u0c47\u0c26\u0c28\u0c3f \u0c24\u0c46\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c3f.  \u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c15\u0c47 &#8216; \u0c35\u0c3f\u0c28\u0c2f \u0c35\u0c3f\u0c27\u0c47\u0c2f \u0c30\u0c3e\u0c2e , \u0c0e\u0c2b\u0c4d 2, \u0c0e\u0c28\u0c4d\u0c1f\u0c40\u0c06\u0c30\u0c4d \u0c15\u0c25\u0c3e\u0c28\u0c3e\u0c2f\u0c15\u0c41\u0c21\u0c41&#8217; \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c32\u0c41 \u0c38\u0c02\u0c15\u0c4d\u0c30\u0c3e\u0c02\u0c24\u0c3f \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c28\u0c41 \u0c15\u0c28\u0c4d\u0c2b\u0c30\u0c4d\u0c2e\u0c4d \u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f.  \u0c2e\u0c30\u0c3f \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c32\u0c24\u0c4b \u0c2a\u0c4b\u0c1f\u0c40 \u0c2a\u0c21\u0c3f \u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c28\u0c41  \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c38\u0c47 \u0c38\u0c3e\u0c39\u0c38\u0c02 \u0c1a\u0c47\u0c2f\u0c32\u0c47\u0c30\u0c41 \u0c15\u0c28\u0c41\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c1a\u0c3f\u0c35\u0c30\u0c3f \u0c35\u0c3e\u0c30\u0c02\u0c32\u0c4b \u0c2a\u0c4d\u0c30\u0c47\u0c15\u0c4d\u0c37\u0c15\u0c41\u0c32\u0c2e\u0c41\u0c02\u0c26\u0c41\u0c15\u0c41 \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c05\u0c35\u0c15\u0c3e\u0c36\u0c3e\u0c32\u0c41 \u0c35\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f.  \u0c24\u0c4d\u0c35\u0c30\u0c32\u0c4b\u0c28\u0c47 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c24\u0c47\u0c26\u0c3f \u0c2b\u0c48 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c30\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. <\/p>\n<p>\u0c30\u0c4a\u0c2e\u0c3e\u0c02\u0c1f\u0c3f\u0c15\u0c4d \u0c0e\u0c02\u0c1f\u0c30\u0c4d\u0c1f\u0c48\u0c28\u0c30\u0c4d \u0c17\u0c3e \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c41\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c28\u0c3f\u0c27\u0c3f \u0c05\u0c17\u0c30\u0c4d\u0c35\u0c3e\u0c32\u0c4d \u0c15\u0c25\u0c3e\u0c28\u0c3e\u0c2f\u0c3f\u0c15\u0c17\u0c3e \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c02\u0c26\u0c3f. \u0c24\u0c2e\u0c28\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c02 \u0c05\u0c02\u0c26\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41.   \u0c0e\u0c38\u0c4d\u0c35\u0c3f\u0c38\u0c40\u0c38\u0c40 \u0c2a\u0c24\u0c3e\u0c15\u0c02 \u0c2b\u0c48  \u0c2c\u0c3f \u0c35\u0c3f \u0c0e\u0c38\u0c4d \u0c0e\u0c28\u0c4d \u0c2a\u0c4d\u0c30\u0c38\u0c3e\u0c26\u0c4d \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41.  \u0c07\u0c15 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c35\u0c30\u0c15\u0c41 \u0c38\u0c3e\u0c32\u0c3f\u0c21\u0c4d \u0c39\u0c3f\u0c1f\u0c4d \u0c32\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c24\u0c4b \u0c06  \u0c32\u0c4b\u0c1f\u0c41\u0c28\u0c41 \u0c24\u0c40\u0c30\u0c4d\u0c1a\u0c41\u0c15\u0c4b\u0c35\u0c3e\u0c32\u0c28\u0c3f \u0c2d\u0c3e\u0c35\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 &#8216;\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41&#8217; \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. &#8216;\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e&#8217; \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":294469,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,4],"tags":[],"class_list":["post-294468","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-mnews"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 &#039;\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41&#039; \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. &#039;\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e&#039; \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"123telugu\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Telugu Cinema News in Telugu\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 &#039;\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41&#039; \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. &#039;\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e&#039; \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-07T10:00:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-07T10:18:49+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/123telugu\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@123telugu\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 &#039;\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41&#039; \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. &#039;\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e&#039; \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#article\",\"name\":\"\\u0c2e\\u0c3f\\u0c38\\u0c4d\\u0c1f\\u0c30\\u0c4d \\u0c2e\\u0c1c\\u0c4d\\u0c28\\u0c41 \\u0c13 \\u0c15\\u0c4d\\u0c32\\u0c3e\\u0c30\\u0c3f\\u0c1f\\u0c40 \\u0c07\\u0c1a\\u0c4d\\u0c1a\\u0c3e\\u0c21\\u0c41 ! | Latest Telugu Movie News, Reviews, OTT, OTT Reviews, Ratings\",\"headline\":\"\\u0c2e\\u0c3f\\u0c38\\u0c4d\\u0c1f\\u0c30\\u0c4d \\u0c2e\\u0c1c\\u0c4d\\u0c28\\u0c41 \\u0c13 \\u0c15\\u0c4d\\u0c32\\u0c3e\\u0c30\\u0c3f\\u0c1f\\u0c40 \\u0c07\\u0c1a\\u0c4d\\u0c1a\\u0c3e\\u0c21\\u0c41 !\",\"author\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/majnue.jpg\",\"width\":280,\"height\":397},\"datePublished\":\"2018-11-07T15:30:10+05:30\",\"dateModified\":\"2018-11-07T15:48:49+05:30\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#webpage\"},\"articleSection\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41, \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"position\":2,\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"position\":3,\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#listItem\",\"name\":\"\\u0c2e\\u0c3f\\u0c38\\u0c4d\\u0c1f\\u0c30\\u0c4d \\u0c2e\\u0c1c\\u0c4d\\u0c28\\u0c41 \\u0c13 \\u0c15\\u0c4d\\u0c32\\u0c3e\\u0c30\\u0c3f\\u0c1f\\u0c40 \\u0c07\\u0c1a\\u0c4d\\u0c1a\\u0c3e\\u0c21\\u0c41 !\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#listItem\",\"position\":4,\"name\":\"\\u0c2e\\u0c3f\\u0c38\\u0c4d\\u0c1f\\u0c30\\u0c4d \\u0c2e\\u0c1c\\u0c4d\\u0c28\\u0c41 \\u0c13 \\u0c15\\u0c4d\\u0c32\\u0c3e\\u0c30\\u0c3f\\u0c1f\\u0c40 \\u0c07\\u0c1a\\u0c4d\\u0c1a\\u0c3e\\u0c21\\u0c41 !\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\",\"name\":\"123telugu.com\",\"description\":\"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/new_big_tel.png\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/123teluguofficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew\",\"name\":\"123telugu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#webpage\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html\",\"name\":\"\\u0c2e\\u0c3f\\u0c38\\u0c4d\\u0c1f\\u0c30\\u0c4d \\u0c2e\\u0c1c\\u0c4d\\u0c28\\u0c41 \\u0c13 \\u0c15\\u0c4d\\u0c32\\u0c3e\\u0c30\\u0c3f\\u0c1f\\u0c40 \\u0c07\\u0c1a\\u0c4d\\u0c1a\\u0c3e\\u0c21\\u0c41 ! | Latest Telugu Movie News, Reviews, OTT, OTT Reviews, Ratings\",\"description\":\"\\u0c2f\\u0c41\\u0c35 \\u0c39\\u0c40\\u0c30\\u0c4b \\u0c05\\u0c15\\u0c4d\\u0c15\\u0c3f\\u0c28\\u0c47\\u0c28\\u0c3f \\u0c05\\u0c16\\u0c3f\\u0c32\\u0c4d \\u0c28\\u0c1f\\u0c3f\\u0c38\\u0c4d\\u0c24\\u0c41\\u0c28\\u0c4d\\u0c28 \\u0c2e\\u0c42\\u0c21\\u0c35 \\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02 '\\u0c2e\\u0c3f\\u0c38\\u0c4d\\u0c1f\\u0c30\\u0c4d \\u0c2e\\u0c1c\\u0c4d\\u0c28\\u0c41' \\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02 \\u0c2f\\u0c4a\\u0c15\\u0c4d\\u0c15 \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d \\u0c24\\u0c41\\u0c26\\u0c3f \\u0c26\\u0c36\\u0c15\\u0c41 \\u0c1a\\u0c47\\u0c30\\u0c41\\u0c15\\u0c41\\u0c02\\u0c26\\u0c3f. \\u0c2e\\u0c30\\u0c3f\\u0c15\\u0c4a\\u0c28\\u0c4d\\u0c28\\u0c3f \\u0c30\\u0c4b\\u0c1c\\u0c41\\u0c32\\u0c4d\\u0c32\\u0c4b \\u0c08 \\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02 \\u0c2f\\u0c4a\\u0c15\\u0c4d\\u0c15 \\u0c37\\u0c42\\u0c1f\\u0c3f\\u0c02\\u0c17\\u0c4d \\u0c2a\\u0c42\\u0c30\\u0c4d\\u0c24\\u0c3f\\u0c15\\u0c3e\\u0c28\\u0c41\\u0c02\\u0c26\\u0c3f. '\\u0c24\\u0c4a\\u0c32\\u0c3f\\u0c2a\\u0c4d\\u0c30\\u0c47\\u0c2e' \\u0c2b\\u0c47\\u0c2e\\u0c4d \\u0c35\\u0c46\\u0c02\\u0c15\\u0c40 \\u0c05\\u0c1f\\u0c4d\\u0c32\\u0c42\\u0c30\\u0c3f \\u0c24\\u0c46\\u0c30\\u0c15\\u0c46\\u0c15\\u0c4d\\u0c15\\u0c3f\\u0c38\\u0c4d\\u0c24\\u0c41\\u0c28\\u0c4d\\u0c28 \\u0c08\\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02\\u0c32\\u0c4b \\u0c05\\u0c16\\u0c3f\\u0c32\\u0c4d \\u0c2a\\u0c4d\\u0c32\\u0c47 \\u0c2c\\u0c3e\\u0c2f\\u0c4d \\u0c2a\\u0c3e\\u0c24\\u0c4d\\u0c30\\u0c32\\u0c4b \\u0c28\\u0c1f\\u0c3f\\u0c38\\u0c4d\\u0c24\\u0c41\\u0c28\\u0c4d\\u0c28\\u0c3e\\u0c21\\u0c41. \\u0c07\\u0c15 \\u0c08 \\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02 \\u0c35\\u0c3f\\u0c21\\u0c41\\u0c26\\u0c32\\u0c48 \\u0c2b\\u0c48 \\u0c12\\u0c15 \\u0c15\\u0c4d\\u0c32\\u0c3e\\u0c30\\u0c3f\\u0c1f\\u0c40 \\u0c35\\u0c1a\\u0c4d\\u0c1a\\u0c3f\\u0c02\\u0c26\\u0c3f. \\u0c08\\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c3e\\u0c28\\u0c4d\\u0c28\\u0c3f \\u0c35\\u0c1a\\u0c4d\\u0c1a\\u0c47 \\u0c0f\\u0c21\\u0c3e\\u0c26\\u0c3f \\u0c1c\\u0c28\\u0c35\\u0c30\\u0c3f \\u0c32\\u0c4b \\u0c35\\u0c3f\\u0c21\\u0c41\\u0c26\\u0c32 \\u0c1a\\u0c47\\u0c2f\\u0c28\\u0c41\\u0c28\\u0c4d\\u0c28\\u0c3e\\u0c30\\u0c28\\u0c3f \\u0c15\\u0c4a\\u0c26\\u0c4d\\u0c26\\u0c40 \\u0c38\\u0c47\\u0c2a\\u0c1f\\u0c3f \\u0c15\\u0c4d\\u0c30\\u0c3f\\u0c24\\u0c02 \\u0c05\\u0c27\\u0c3f\\u0c15\\u0c3e\\u0c30\\u0c15\\u0c02\\u0c17\\u0c3e \\u0c2a\\u0c4d\\u0c30\\u0c15\\u0c1f\\u0c3f\\u0c02\\u0c1a\\u0c3e\\u0c30\\u0c41. \\u0c05\\u0c2f\\u0c3f\\u0c24\\u0c47 \\u0c08\\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c02\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/majnue.jpg\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html\\\/#mainImage\",\"width\":280,\"height\":397},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/mr-majnu-will-be-release-in-next-year-january.html#mainImage\"},\"datePublished\":\"2018-11-07T15:30:10+05:30\",\"dateModified\":\"2018-11-07T15:48:49+05:30\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#website\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/\",\"name\":\"123telugu.com\",\"alternateName\":\"123telugu\",\"description\":\"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 ! | Latest Telugu Movie News, Reviews, OTT, OTT Reviews, Ratings","description":"\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 '\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41' \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. '\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e' \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02","canonical_url":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#article","name":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 ! | Latest Telugu Movie News, Reviews, OTT, OTT Reviews, Ratings","headline":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !","author":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"publisher":{"@id":"https:\/\/www.123telugu.com\/telugu\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg","width":280,"height":397},"datePublished":"2018-11-07T15:30:10+05:30","dateModified":"2018-11-07T15:48:49+05:30","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#webpage"},"isPartOf":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#webpage"},"articleSection":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41, \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"},{"@type":"BreadcrumbList","@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu#listItem","position":1,"name":"Home","item":"https:\/\/www.123telugu.com\/telugu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","position":2,"name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","item":"https:\/\/www.123telugu.com\/telugu\/category\/news","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","position":3,"name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","item":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#listItem","name":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#listItem","position":4,"name":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !","previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}}]},{"@type":"Organization","@id":"https:\/\/www.123telugu.com\/telugu\/#organization","name":"123telugu.com","description":"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings","url":"https:\/\/www.123telugu.com\/telugu\/","logo":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2019\/09\/new_big_tel.png","@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html\/#organizationLogo"},"image":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/123teluguofficial\/"]},{"@type":"Person","@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author","url":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew","name":"123telugu"},{"@type":"WebPage","@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#webpage","url":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html","name":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 ! | Latest Telugu Movie News, Reviews, OTT, OTT Reviews, Ratings","description":"\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 '\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41' \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. '\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e' \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.123telugu.com\/telugu\/#website"},"breadcrumb":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#breadcrumblist"},"author":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"creator":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"image":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg","@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html\/#mainImage","width":280,"height":397},"primaryImageOfPage":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html#mainImage"},"datePublished":"2018-11-07T15:30:10+05:30","dateModified":"2018-11-07T15:48:49+05:30"},{"@type":"WebSite","@id":"https:\/\/www.123telugu.com\/telugu\/#website","url":"https:\/\/www.123telugu.com\/telugu\/","name":"123telugu.com","alternateName":"123telugu","description":"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.123telugu.com\/telugu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Telugu Cinema News in Telugu","og:type":"article","og:title":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !","og:description":"\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 '\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41' \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. '\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e' \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02","og:url":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html","og:image":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg","og:image:secure_url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg","article:published_time":"2018-11-07T10:00:10+00:00","article:modified_time":"2018-11-07T10:18:49+00:00","article:publisher":"https:\/\/www.facebook.com\/123telugu","twitter:card":"summary","twitter:site":"@123telugu","twitter:title":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !","twitter:description":"\u0c2f\u0c41\u0c35 \u0c39\u0c40\u0c30\u0c4b \u0c05\u0c15\u0c4d\u0c15\u0c3f\u0c28\u0c47\u0c28\u0c3f \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2e\u0c42\u0c21\u0c35 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 '\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41' \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c41\u0c26\u0c3f \u0c26\u0c36\u0c15\u0c41 \u0c1a\u0c47\u0c30\u0c41\u0c15\u0c41\u0c02\u0c26\u0c3f. \u0c2e\u0c30\u0c3f\u0c15\u0c4a\u0c28\u0c4d\u0c28\u0c3f \u0c30\u0c4b\u0c1c\u0c41\u0c32\u0c4d\u0c32\u0c4b \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c2f\u0c4a\u0c15\u0c4d\u0c15 \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. '\u0c24\u0c4a\u0c32\u0c3f\u0c2a\u0c4d\u0c30\u0c47\u0c2e' \u0c2b\u0c47\u0c2e\u0c4d \u0c35\u0c46\u0c02\u0c15\u0c40 \u0c05\u0c1f\u0c4d\u0c32\u0c42\u0c30\u0c3f \u0c24\u0c46\u0c30\u0c15\u0c46\u0c15\u0c4d\u0c15\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02\u0c32\u0c4b \u0c05\u0c16\u0c3f\u0c32\u0c4d \u0c2a\u0c4d\u0c32\u0c47 \u0c2c\u0c3e\u0c2f\u0c4d \u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c32\u0c4b \u0c28\u0c1f\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c07\u0c15 \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02 \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32\u0c48 \u0c2b\u0c48 \u0c12\u0c15 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c47 \u0c0f\u0c21\u0c3e\u0c26\u0c3f \u0c1c\u0c28\u0c35\u0c30\u0c3f \u0c32\u0c4b \u0c35\u0c3f\u0c21\u0c41\u0c26\u0c32 \u0c1a\u0c47\u0c2f\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c28\u0c3f \u0c15\u0c4a\u0c26\u0c4d\u0c26\u0c40 \u0c38\u0c47\u0c2a\u0c1f\u0c3f \u0c15\u0c4d\u0c30\u0c3f\u0c24\u0c02 \u0c05\u0c27\u0c3f\u0c15\u0c3e\u0c30\u0c15\u0c02\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c15\u0c1f\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c05\u0c2f\u0c3f\u0c24\u0c47 \u0c08\u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c02","twitter:image":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg"},"aioseo_meta_data":{"post_id":"294468","title":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 ! | #site_title","description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !","og_description":"","og_object_type":"article","og_image_type":"custom_image","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"custom_image","twitter_image_url":null,"twitter_image_custom_url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2018\/11\/majnue.jpg","twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-12 06:50:20","updated":"2022-10-18 03:05:34","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\/category\/news\" title=\"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41\">\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews\" title=\"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41\">\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.123telugu.com\/telugu"},{"label":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","link":"https:\/\/www.123telugu.com\/telugu\/category\/news"},{"label":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","link":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews"},{"label":"\u0c2e\u0c3f\u0c38\u0c4d\u0c1f\u0c30\u0c4d \u0c2e\u0c1c\u0c4d\u0c28\u0c41 \u0c13 \u0c15\u0c4d\u0c32\u0c3e\u0c30\u0c3f\u0c1f\u0c40 \u0c07\u0c1a\u0c4d\u0c1a\u0c3e\u0c21\u0c41 !","link":"https:\/\/www.123telugu.com\/telugu\/news\/mr-majnu-will-be-release-in-next-year-january.html"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/294468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/comments?post=294468"}],"version-history":[{"count":0,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/294468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/media\/294469"}],"wp:attachment":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/media?parent=294468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/categories?post=294468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/tags?post=294468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}