{"id":91615,"date":"2014-01-09T23:30:34","date_gmt":"2014-01-09T18:00:34","guid":{"rendered":"http:\/\/www.123telugu.com\/telugu\/?p=91615"},"modified":"2014-01-10T00:03:11","modified_gmt":"2014-01-09T18:33:11","slug":"thaman-joins-charan-krishna-vamsi-film","status":"publish","type":"post","link":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html","title":{"rendered":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d"},"content":{"rendered":"<p><a href=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-69240\" alt=\"SS-Thaman\" src=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg\" width=\"420\" height=\"350\" srcset=\"https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg 420w, https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1-300x250.jpg 300w, https:\/\/www.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1-266x222.jpg 266w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a><br \/>\n\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. <!--more-->\u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41<\/p>\n<p>\u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f<\/p>\n<p>\u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c2c\u0c02\u0c27\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c30\u0c46\u0c17\u0c4d\u0c2f\u0c41\u0c32\u0c30\u0c4d \u0c37\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c24\u0c4d\u0c35\u0c30\u0c32\u0c4b \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c02\u0c15\u0c3e\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c35\u0c3f\u0c1c\u0c2f\u0c3e\u0c32\u0c41 \u0c32\u0c47\u0c15 \u0c21\u0c40\u0c32\u0c3e \u0c2a\u0c21\u0c3f\u0c2a\u0c4b\u0c2f\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40\u0c15\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3f\u0c1c\u0c2f\u0c02 \u0c1a\u0c3e\u0c32\u0c3e \u0c05\u0c35\u0c38\u0c30\u0c02<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,4],"tags":[],"class_list":["post-91615","post","type-post","status-publish","format-standard","category-news","category-mnews"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. \u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"123telugu\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Telugu Cinema News in Telugu\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. \u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-09T18:00:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-09T18:33:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/123telugu\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@123telugu\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. \u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#article\",\"name\":\"\\u0c1a\\u0c46\\u0c30\\u0c4d\\u0c30\\u0c40-\\u0c15\\u0c43\\u0c37\\u0c4d\\u0c23 \\u0c35\\u0c02\\u0c36\\u0c40 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41 \\u0c25\\u0c2e\\u0c28\\u0c4d\",\"headline\":\"\\u0c1a\\u0c46\\u0c30\\u0c4d\\u0c30\\u0c40-\\u0c15\\u0c43\\u0c37\\u0c4d\\u0c23 \\u0c35\\u0c02\\u0c36\\u0c40 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41 \\u0c25\\u0c2e\\u0c28\\u0c4d\",\"author\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/SS-Thaman1.jpg\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html\\\/#articleImage\"},\"datePublished\":\"2014-01-09T23:30:34+05:30\",\"dateModified\":\"2014-01-10T00:03:11+05:30\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#webpage\"},\"articleSection\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41, \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"position\":2,\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"position\":3,\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\",\"item\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#listItem\",\"name\":\"\\u0c1a\\u0c46\\u0c30\\u0c4d\\u0c30\\u0c40-\\u0c15\\u0c43\\u0c37\\u0c4d\\u0c23 \\u0c35\\u0c02\\u0c36\\u0c40 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41 \\u0c25\\u0c2e\\u0c28\\u0c4d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news#listItem\",\"name\":\"\\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#listItem\",\"position\":4,\"name\":\"\\u0c1a\\u0c46\\u0c30\\u0c4d\\u0c30\\u0c40-\\u0c15\\u0c43\\u0c37\\u0c4d\\u0c23 \\u0c35\\u0c02\\u0c36\\u0c40 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41 \\u0c25\\u0c2e\\u0c28\\u0c4d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/category\\\/news\\\/mnews#listItem\",\"name\":\"\\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c35\\u0c3e\\u0c30\\u0c4d\\u0c24\\u0c32\\u0c41\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\",\"name\":\"123telugu.com\",\"description\":\"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.123telugu.com\\\/telugu\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/new_big_tel.png\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/123teluguofficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew\",\"name\":\"123telugu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#webpage\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html\",\"name\":\"\\u0c1a\\u0c46\\u0c30\\u0c4d\\u0c30\\u0c40-\\u0c15\\u0c43\\u0c37\\u0c4d\\u0c23 \\u0c35\\u0c02\\u0c36\\u0c40 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41 \\u0c25\\u0c2e\\u0c28\\u0c4d\",\"description\":\"\\u0c24\\u0c28\\u0c41 \\u0c2a\\u0c28\\u0c3f\\u0c1a\\u0c47\\u0c38\\u0c3f\\u0c28 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c32\\u0c15\\u0c41 \\u0c2a\\u0c46\\u0c2a\\u0c4d\\u0c2a\\u0c40 \\u0c1f\\u0c4d\\u0c2f\\u0c42\\u0c28\\u0c4d \\u0c32\\u0c28\\u0c41, \\u0c0e\\u0c28\\u0c46\\u0c30\\u0c4d\\u0c1c\\u0c3f\\u0c1f\\u0c3f\\u0c15\\u0c4d \\u0c38\\u0c02\\u0c17\\u0c40\\u0c24\\u0c3e\\u0c28\\u0c4d\\u0c28\\u0c3f \\u0c07\\u0c35\\u0c4d\\u0c35\\u0c21\\u0c02\\u0c32\\u0c4b \\u0c25\\u0c2e\\u0c28\\u0c4d \\u0c38\\u0c3f\\u0c26\\u0c4d\\u0c27\\u0c39\\u0c38\\u0c4d\\u0c24\\u0c41\\u0c21\\u0c41. \\u0c08 \\u0c38\\u0c02\\u0c17\\u0c40\\u0c24 \\u0c26\\u0c30\\u0c4d\\u0c36\\u0c15\\u0c41\\u0c21\\u0c41 \\u0c24\\u0c28 \\u0c15\\u0c46\\u0c30\\u0c40\\u0c30\\u0c4d \\u0c32\\u0c4b \\u0c2e\\u0c30\\u0c4b\\u0c38\\u0c3e\\u0c30\\u0c3f \\u0c2e\\u0c46\\u0c17\\u0c3e \\u0c2a\\u0c35\\u0c30\\u0c4d \\u0c38\\u0c4d\\u0c1f\\u0c3e\\u0c30\\u0c4d \\u0c30\\u0c3e\\u0c2e\\u0c4d \\u0c1a\\u0c30\\u0c23\\u0c4d \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41 \\u0c38\\u0c02\\u0c17\\u0c40\\u0c24\\u0c3e\\u0c28\\u0c4d\\u0c28\\u0c3f \\u0c05\\u0c02\\u0c26\\u0c3f\\u0c02\\u0c1a\\u0c28\\u0c41\\u0c28\\u0c4d\\u0c28\\u0c3e\\u0c21\\u0c41. \\u0c08 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41 \\u0c15\\u0c43\\u0c37\\u0c4d\\u0c23\\u0c35\\u0c02\\u0c36\\u0c40 \\u0c26\\u0c30\\u0c4d\\u0c36\\u0c15\\u0c41\\u0c21\\u0c41. \\u0c36\\u0c4d\\u0c30\\u0c40\\u0c15\\u0c3e\\u0c02\\u0c24\\u0c4d \\u0c2e\\u0c41\\u0c16\\u0c4d\\u0c2f\\u0c2a\\u0c3e\\u0c24\\u0c4d\\u0c30\\u0c2a\\u0c4b\\u0c37\\u0c3f\\u0c02\\u0c1a\\u0c28\\u0c41\\u0c28\\u0c4d\\u0c28\\u0c3e\\u0c21\\u0c41 \\u0c08 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c32\\u0c4b \\u0c1a\\u0c30\\u0c23\\u0c4d \\u0c38\\u0c30\\u0c38\\u0c28 \\u0c15\\u0c3e\\u0c1c\\u0c32\\u0c4d \\u0c28\\u0c1f\\u0c3f\\u0c02\\u0c1a\\u0c28\\u0c41\\u0c02\\u0c26\\u0c3f. \\u0c38\\u0c4d\\u0c1f\\u0c3e\\u0c30\\u0c4d \\u0c2a\\u0c4d\\u0c30\\u0c4a\\u0c21\\u0c4d\\u0c2f\\u0c42\\u0c38\\u0c30\\u0c4d \\u0c2c\\u0c02\\u0c21\\u0c4d\\u0c32 \\u0c17\\u0c23\\u0c47\\u0c37\\u0c4d \\u0c08 \\u0c1a\\u0c3f\\u0c24\\u0c4d\\u0c30\\u0c28\\u0c3f\\u0c30\\u0c4d\\u0c2e\\u0c3e\\u0c24. \\u0c08 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e \\u0c2d\\u0c3e\\u0c35\\u0c4b\\u0c26\\u0c4d\\u0c35\\u0c47\\u0c17\\u0c3e\\u0c32\\u0c24\\u0c4b \\u0c28\\u0c3f\\u0c02\\u0c21\\u0c3f\\u0c28 \\u0c15\\u0c43\\u0c37\\u0c4d\\u0c23 \\u0c35\\u0c02\\u0c36\\u0c40 \\u0c2e\\u0c3e\\u0c30\\u0c4d\\u0c15\\u0c41 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c17\\u0c3e \\u0c38\\u0c3e\\u0c17\\u0c28\\u0c41\\u0c02\\u0c26\\u0c3f \\u0c08 \\u0c38\\u0c3f\\u0c28\\u0c3f\\u0c2e\\u0c3e\\u0c15\\u0c41\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/news\\\/thaman-joins-charan-krishna-vamsi-film.html#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/author\\\/123rkspnew#author\"},\"datePublished\":\"2014-01-09T23:30:34+05:30\",\"dateModified\":\"2014-01-10T00:03:11+05:30\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#website\",\"url\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/\",\"name\":\"123telugu.com\",\"alternateName\":\"123telugu\",\"description\":\"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.123telugu.com\\\/telugu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","description":"\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. \u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41","canonical_url":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#article","name":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","headline":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","author":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"publisher":{"@id":"https:\/\/www.123telugu.com\/telugu\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg","@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html\/#articleImage"},"datePublished":"2014-01-09T23:30:34+05:30","dateModified":"2014-01-10T00:03:11+05:30","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#webpage"},"isPartOf":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#webpage"},"articleSection":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41, \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"},{"@type":"BreadcrumbList","@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu#listItem","position":1,"name":"Home","item":"https:\/\/www.123telugu.com\/telugu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","position":2,"name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","item":"https:\/\/www.123telugu.com\/telugu\/category\/news","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","position":3,"name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","item":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#listItem","name":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news#listItem","name":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}},{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#listItem","position":4,"name":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","previousItem":{"@type":"ListItem","@id":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews#listItem","name":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41"}}]},{"@type":"Organization","@id":"https:\/\/www.123telugu.com\/telugu\/#organization","name":"123telugu.com","description":"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings","url":"https:\/\/www.123telugu.com\/telugu\/","logo":{"@type":"ImageObject","url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2019\/09\/new_big_tel.png","@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html\/#organizationLogo"},"image":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/123teluguofficial\/"]},{"@type":"Person","@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author","url":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew","name":"123telugu"},{"@type":"WebPage","@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#webpage","url":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html","name":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","description":"\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. \u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.123telugu.com\/telugu\/#website"},"breadcrumb":{"@id":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html#breadcrumblist"},"author":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"creator":{"@id":"https:\/\/www.123telugu.com\/telugu\/author\/123rkspnew#author"},"datePublished":"2014-01-09T23:30:34+05:30","dateModified":"2014-01-10T00:03:11+05:30"},{"@type":"WebSite","@id":"https:\/\/www.123telugu.com\/telugu\/#website","url":"https:\/\/www.123telugu.com\/telugu\/","name":"123telugu.com","alternateName":"123telugu","description":"Telugu Movie News, Movie Reviews, OTT, Reviews, OTT Reviews, Ratings","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.123telugu.com\/telugu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Telugu Cinema News in Telugu","og:type":"article","og:title":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","og:description":"\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. \u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41","og:url":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html","og:image":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg","og:image:secure_url":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg","article:published_time":"2014-01-09T18:00:34+00:00","article:modified_time":"2014-01-09T18:33:11+00:00","article:publisher":"https:\/\/www.facebook.com\/123telugu","twitter:card":"summary_large_image","twitter:site":"@123telugu","twitter:title":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","twitter:description":"\u0c24\u0c28\u0c41 \u0c2a\u0c28\u0c3f\u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c15\u0c41 \u0c2a\u0c46\u0c2a\u0c4d\u0c2a\u0c40 \u0c1f\u0c4d\u0c2f\u0c42\u0c28\u0c4d \u0c32\u0c28\u0c41, \u0c0e\u0c28\u0c46\u0c30\u0c4d\u0c1c\u0c3f\u0c1f\u0c3f\u0c15\u0c4d \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c07\u0c35\u0c4d\u0c35\u0c21\u0c02\u0c32\u0c4b \u0c25\u0c2e\u0c28\u0c4d \u0c38\u0c3f\u0c26\u0c4d\u0c27\u0c39\u0c38\u0c4d\u0c24\u0c41\u0c21\u0c41. \u0c08 \u0c38\u0c02\u0c17\u0c40\u0c24 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41 \u0c24\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c32\u0c4b \u0c2e\u0c30\u0c4b\u0c38\u0c3e\u0c30\u0c3f \u0c2e\u0c46\u0c17\u0c3e \u0c2a\u0c35\u0c30\u0c4d \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c30\u0c3e\u0c2e\u0c4d \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c38\u0c02\u0c17\u0c40\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c05\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c15\u0c43\u0c37\u0c4d\u0c23\u0c35\u0c02\u0c36\u0c40 \u0c26\u0c30\u0c4d\u0c36\u0c15\u0c41\u0c21\u0c41. \u0c36\u0c4d\u0c30\u0c40\u0c15\u0c3e\u0c02\u0c24\u0c4d \u0c2e\u0c41\u0c16\u0c4d\u0c2f\u0c2a\u0c3e\u0c24\u0c4d\u0c30\u0c2a\u0c4b\u0c37\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c21\u0c41 \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c32\u0c4b \u0c1a\u0c30\u0c23\u0c4d \u0c38\u0c30\u0c38\u0c28 \u0c15\u0c3e\u0c1c\u0c32\u0c4d \u0c28\u0c1f\u0c3f\u0c02\u0c1a\u0c28\u0c41\u0c02\u0c26\u0c3f. \u0c38\u0c4d\u0c1f\u0c3e\u0c30\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c21\u0c4d\u0c2f\u0c42\u0c38\u0c30\u0c4d \u0c2c\u0c02\u0c21\u0c4d\u0c32 \u0c17\u0c23\u0c47\u0c37\u0c4d \u0c08 \u0c1a\u0c3f\u0c24\u0c4d\u0c30\u0c28\u0c3f\u0c30\u0c4d\u0c2e\u0c3e\u0c24. \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c2d\u0c3e\u0c35\u0c4b\u0c26\u0c4d\u0c35\u0c47\u0c17\u0c3e\u0c32\u0c24\u0c4b \u0c28\u0c3f\u0c02\u0c21\u0c3f\u0c28 \u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c2e\u0c3e\u0c30\u0c4d\u0c15\u0c41 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c17\u0c3e \u0c38\u0c3e\u0c17\u0c28\u0c41\u0c02\u0c26\u0c3f \u0c08 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41","twitter:image":"https:\/\/cdn.123telugu.com\/telugu\/wp-content\/uploads\/2013\/06\/SS-Thaman1.jpg"},"aioseo_meta_data":{"post_id":"91615","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-11-15 10:24:09","updated":"2025-06-12 11:40:17","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\/category\/news\" title=\"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41\">\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews\" title=\"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41\">\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.123telugu.com\/telugu"},{"label":"\u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","link":"https:\/\/www.123telugu.com\/telugu\/category\/news"},{"label":"\u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e \u0c35\u0c3e\u0c30\u0c4d\u0c24\u0c32\u0c41","link":"https:\/\/www.123telugu.com\/telugu\/category\/news\/mnews"},{"label":"\u0c1a\u0c46\u0c30\u0c4d\u0c30\u0c40-\u0c15\u0c43\u0c37\u0c4d\u0c23 \u0c35\u0c02\u0c36\u0c40 \u0c38\u0c3f\u0c28\u0c3f\u0c2e\u0c3e\u0c15\u0c41 \u0c25\u0c2e\u0c28\u0c4d","link":"https:\/\/www.123telugu.com\/telugu\/news\/thaman-joins-charan-krishna-vamsi-film.html"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/91615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/comments?post=91615"}],"version-history":[{"count":0,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/posts\/91615\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/media?parent=91615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/categories?post=91615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.123telugu.com\/telugu\/wp-json\/wp\/v2\/tags?post=91615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}